{"id":1830,"date":"2016-01-22T08:48:18","date_gmt":"2016-01-22T08:48:18","guid":{"rendered":"http:\/\/www.humanium.org\/es\/?page_id=1830"},"modified":"2025-12-13T21:05:32","modified_gmt":"2025-12-13T21:05:32","slug":"sudafrica","status":"publish","type":"page","link":"https:\/\/www.humanium.org\/es\/sudafrica\/","title":{"rendered":"Ni\u00f1os de Sud\u00e1frica"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Descubriendo los Derechos del Ni\u00f1o en Sud\u00e1frica<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1786480814.jpg\" alt=\"\" class=\"wp-image-16378\" srcset=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1786480814.jpg 200w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1786480814-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1268864137.jpg\" alt=\"\" class=\"wp-image-16379\" srcset=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1268864137.jpg 200w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1268864137-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sud\u00e1frica ratific\u00f3 la Convenci\u00f3n sobre los Derechos del Ni\u00f1o en junio de 1995. Un a\u00f1o despu\u00e9s, el gobierno sudafricano especific\u00f3 los derechos de los ni\u00f1os en la Declaraci\u00f3n de Derechos de la Constituci\u00f3n, secci\u00f3n 28: \u00abtodo ni\u00f1o tiene derecho a una <a href=\"https:\/\/www.humanium.org\/es\/derecho-alimentacion\/\">nutrici\u00f3n<\/a> b\u00e1sica, <a href=\"https:\/\/www.humanium.org\/es\/derecho-proteccion\/\">refugio<\/a>, atenci\u00f3n m\u00e9dica y servicios sociales, as\u00ed como el derecho a ser protegido contra el maltrato, la negligencia, el <a href=\"https:\/\/www.humanium.org\/es\/abuso-infantil\/\">abuso <\/a>o la humillaci\u00f3n\u00bb. A pesar de estas promesas, los ni\u00f1os de diferentes or\u00edgenes de Sud\u00e1frica nacen en desigualdad de oportunidades; algunos afectados por la<a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/pobreza\/\"> pobreza<\/a>, la<a href=\"https:\/\/www.humanium.org\/es\/salud\/%20\"> mala salud<\/a> y un dif\u00edcil acceso a la educaci\u00f3n.<\/strong><\/p>\n\n\n\n<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d13500832.286263715!2d18.247902564563827!3d-34.296954051962786!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x1c34a689d9ee1251%3A0xe85d630c1fa4e8a0!2sSouth%20Africa!5e0!3m2!1sen!2sin!4v1636631816594!5m2!1sen!2sin\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\"><\/iframe>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Poblaci\u00f3n:<\/strong> 59,3 millones<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Poblaci\u00f3n de 0 a 14 a\u00f1os:<\/strong> 28,8%<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Esperanza de vida: <\/strong>64,1 a\u00f1os<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tasa de mortalidad de menores de 5 a\u00f1os:<\/strong> 34,5\u2030<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Sud\u00e1frica a grandes rasgos <\/strong><strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La Rep\u00fablica de Sud\u00e1frica es un pa\u00eds ubicado en <a href=\"https:\/\/www.humanium.org\/es\/africa\/\">\u00c0frica del Sur<\/a> y tiene una poblaci\u00f3n de 60 millones de personas. Sud\u00e1frica es un pa\u00eds en desarrollo con la tercera econom\u00eda m\u00e1s grande de \u00c1frica. Las desigualdades que existen dentro de este pa\u00eds multicultural y multi\u00e9tnico provienen de la era del <em>apartheid<\/em>, impuesto en 1948 por el Partido Nacional, que lanz\u00f3 la segregaci\u00f3n racial oficial entre blancos y negros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los activistas del <em>antiapartheid<\/em> lucharon para derogar estas leyes discriminatorias a mediados de la d\u00e9cada de 1980 y, en abril de 1994, los sudafricanos tuvieron las primeras elecciones democr\u00e1ticas, en las que votaron por mayor\u00eda por el primer presidente negro del pa\u00eds, Nelson Mandela. Durante su mandato, Mandela prest\u00f3 mucha atenci\u00f3n a los ni\u00f1os y presion\u00f3 para que sus ciudadanos se acercaran a la infancia para apoyar su crecimiento en medio del dolor y del sufrimiento. Pero a pesar de sus metas y objetivos, los derechos de los ni\u00f1os en Sud\u00e1frica siguen desatendidos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Estado de los derechos del ni\u00f1o<\/strong><a href=\"#_ftn1\"><strong><sup><strong><sup>[1]<\/sup><\/strong><\/sup><\/strong><\/a><strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s del <em>apartheid<\/em>, el gobierno de Mandela trabaj\u00f3 para brindar un apoyo adecuado a los ni\u00f1os. La secci\u00f3n 28 de la Declaraci\u00f3n de Derechos describe el <a href=\"https:\/\/www.humanium.org\/es\/derecho-vida\/\">derecho de los ni\u00f1os a una vida segura<\/a>:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abTodo ni\u00f1o tiene derecho a:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Un <a href=\"https:\/\/www.humanium.org\/es\/derecho-identidad\/\">nombre y una nacionalidad <\/a>de nacimiento. <a href=\"https:\/\/www.humanium.org\/es\/derecho-proteccion\/\">Cuidado familiar o cuidado parental<\/a>, o al cuidado alternativo apropiado cuando se saca del entorno familiar.<\/li>\n\n\n\n<li><a href=\"https:\/\/www.humanium.org\/es\/derecho-alimentacion\/\">Nutrici\u00f3n<\/a> b\u00e1sica, <a href=\"https:\/\/www.humanium.org\/es\/derechos\/\">refugio<\/a>, servicios de atenci\u00f3n m\u00e9dica b\u00e1sica y servicios sociales.<\/li>\n\n\n\n<li>Estar protegido contra el maltrato, la negligencia, el <a href=\"https:\/\/www.humanium.org\/es\/abuso-infantil\/\">abuso <\/a>o la humillaci\u00f3n.<\/li>\n\n\n\n<li>Estar protegido contra las pr\u00e1cticas de explotaci\u00f3n <a href=\"https:\/\/www.humanium.org\/es\/trabajo-infantil\/\">laboral<\/a>.<\/li>\n\n\n\n<li>No estar obligado o autorizado a realizar un trabajo o proporcionar servicios que sean inapropiados para una persona de la edad de ese ni\u00f1o o que pongan en riesgo su bienestar, <a href=\"https:\/\/www.humanium.org\/es\/derecho-educacion\/%20\">educaci\u00f3n<\/a>, salud f\u00edsica o mental o desarrollo espiritual, moral o social.<\/li>\n\n\n\n<li>No ser <a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/justicia\/ninos-detenidos\/\">detenido<\/a>, excepto como medida de \u00faltimo recurso, en cuyo caso, adem\u00e1s de los derechos de los que disfruta un ni\u00f1o seg\u00fan las secciones 12 y 35, el ni\u00f1o puede ser detenido solo por el periodo de tiempo m\u00e1s corto y apropiado, y tiene derecho a estar separado de las personas detenidas mayores de 18 a\u00f1os.<\/li>\n\n\n\n<li>Ser tratados de una manera y mantenidos en unas condiciones que tengan en cuenta la edad del ni\u00f1o, as\u00ed como asignarles, a expensas del estado, un abogado del estado en <a href=\"https:\/\/www.humanium.org\/es\/justicia\/\">procesos civiles <\/a>que afecten al ni\u00f1o, cuando lo contrario constituyera una injusticia notoria .<\/li>\n\n\n\n<li>No ser utilizado directamente en <a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/violencia\/ninos-guerra\/\">conflictos armados,<\/a> y estar protegido en tiempos de conflicto armado\u00bb (Tribunal Constitucional de Sud\u00e1frica, s. f.).<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"580\" src=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1270098124-1024x580.jpg\" alt=\"\" class=\"wp-image-16382\" style=\"width:373px;height:211px\" srcset=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1270098124-1024x580.jpg 1024w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1270098124-300x170.jpg 300w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1270098124-768x435.jpg 768w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1270098124-1536x871.jpg 1536w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1270098124-2048x1161.jpg 2048w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1270098124-830x470.jpg 830w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1270098124-230x130.jpg 230w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1270098124-350x198.jpg 350w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1270098124-480x272.jpg 480w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de la ratificaci\u00f3n de la CDN, Sud\u00e1frica tambi\u00e9n promulg\u00f3 la Ley de Condiciones B\u00e1sicas de Empleo, que proh\u00edbe<a href=\"https:\/\/www.humanium.org\/es\/trabajo-infantil\/\"> el trabajo infantil<\/a> de menores de 15 a\u00f1os (Tribunal Constitucional de Sud\u00e1frica, s. f.). Sud\u00e1frica tambi\u00e9n es signataria de la Carta Africana sobre los Derechos y el Bienestar del Ni\u00f1o, cuyo art\u00edculo 3 reconoce el derecho del ni\u00f1o a una infancia feliz, independientemente de su origen racial, \u00e9tnico, sexual, religioso, o de nacimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, la Ley sobre la Violencia Dom\u00e9stica de 1998 protege a los ni\u00f1os<a href=\"https:\/\/www.humanium.org\/es\/violencia\/\"> contra los abusadores dom\u00e9sticos<\/a>. La Propuesta de Ley de la Infancia de 2005, destinada a reemplazar la Ley de Protecci\u00f3n del Ni\u00f1o de 1983, estipulaba el derecho de los ni\u00f1os a la privacidad y la protecci\u00f3n, y tambi\u00e9n propuso nuevos proyectos de financiaci\u00f3n para programas de desarrollo de la primera infancia. Al hacer eso, estas leyes tienen como objetivo proporcionar un enfoque hol\u00edstico de los ni\u00f1os. A pesar de los esfuerzos de Sud\u00e1frica, los derechos de la infancia siguen estando muy desatendidos (Tribunal Constitucional de Sud\u00e1frica, s. f.).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Tratar las necesidades de los ni\u00f1os y las ni\u00f1as<\/strong><strong><\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.humanium.org\/es\/derecho-educacion\/%20\">Derecho a la educaci\u00f3n<\/a><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s del <em>apartheid<\/em>, Sud\u00e1frica logr\u00f3 un gran progreso al proporcionar<a href=\"https:\/\/www.humanium.org\/es\/derecho-educacion\/%20\"> el derecho a la educaci\u00f3n<\/a>. El progreso ha sido prominente en la educaci\u00f3n preescolar, primaria y secundaria. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abEl n\u00famero de ni\u00f1os menores de cinco a\u00f1os que asisten a un centro de desarrollo de la primera infancia (DPI) o preescolar ha aumentado a uno de cada tres en lugar de uno de cada diez, desde 2002. La asistencia a la escuela primaria es del 99%, un 3% m\u00e1s que en 2002. La asistencia a la escuela secundaria ha aumentado del 88% en 2002 al 90%, con una paridad de g\u00e9nero notable. <a href=\"https:\/\/www.humanium.org\/es\/infancia-con-discapacidades\/\">Los ni\u00f1os con discapacidades <\/a>est\u00e1n mejor incluidos dentro del sistema escolar y ahora representan el 5 por ciento de la poblaci\u00f3n total de ni\u00f1os que asisten a la escuela.\u00bb <\/p>\n<cite>&#8211; UNICEF Sud\u00e1frica, s. f.<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, a pesar de estos cambios, el acceso de los ni\u00f1os a una educaci\u00f3n de calidad sigue influenciado por la<a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/pobreza\/\"> pobreza<\/a> y la desigualdad. Sin una mano de obra docente calificada, una educaci\u00f3n de calidad y una<a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/pobreza\/\"> alta pobreza<\/a>, el<a href=\"https:\/\/www.humanium.org\/es\/derecho-educacion\/%20\"> acceso de los ni\u00f1os a la educaci\u00f3n<\/a> les impide formar la base para el \u00abdesarrollo futuro y la capacidad de aprendizaje\u00bb de la infancia (UNICEF Sud\u00e1frica, s. f.). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las tasas de abandono escolar tambi\u00e9n son significativas: m\u00e1s del 25% de los ni\u00f1os abandonan la escuela, la mayor\u00eda de zonas pobres. <a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/discriminacion\/derechos-ninas\/\">Las ni\u00f1as <\/a>est\u00e1n particularmente sobrerrepresentadas en esta estad\u00edstica, lo que lleva a una brecha de g\u00e9nero cada vez mayor en las escuelas. Adem\u00e1s, el gobierno ha prometido eliminar los costos de matr\u00edcula para el 60% de los ni\u00f1os m\u00e1s pobres, pero algunas familias a\u00fan tienen que cubrir los costos de otros gastos relacionados con la escuela (UNICEF Sud\u00e1frica, s. f.).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La<a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/discriminacion\/derechos-ninas\/\"> desigualdad de g\u00e9nero<\/a> afecta a las chicas j\u00f3venes; esta brecha de g\u00e9nero es particularmente fuerte en las carreras relacionadas con la ciencia, la tecnolog\u00eda, la ingenier\u00eda y las matem\u00e1ticas (STEM, por sus siglas en ingl\u00e9s), donde menos del 30% de las chicas j\u00f3venes se grad\u00faan de instituciones terciarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En febrero de 2020, Amnist\u00eda Internacional public\u00f3 un informe sobre las flagrantes desigualdades en las escuelas sudafricanas, que obstaculizan el <a href=\"https:\/\/www.humanium.org\/es\/derecho-educacion\/%20\">acceso de los ni\u00f1os a la educaci\u00f3n.<\/a> Amnist\u00eda explica que el acceso a una buena educaci\u00f3n depende de la riqueza, el color de la piel y la residencia del ni\u00f1o, lo que perpet\u00faa a\u00fan m\u00e1s las decisiones pol\u00edticas tomadas durante la era del <em>apartheid<\/em>. La directora ejecutiva de Amnist\u00eda Internacional Sud\u00e1frica, Shenilla Mohamed, espera que el gobierno sudafricano cambie su forma de actuar. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abEl derecho a una educaci\u00f3n de calidad incluye tener una escuela donde el alumnado est\u00e9 seguro para aprender y tenga la infraestructura y las instalaciones adecuadas para hacerlo, pero nuestra investigaci\u00f3n revela que esta no es la realidad para muchos alumnos en el pa\u00eds.\u00bb <\/p>\n<cite>&#8211; Amnist\u00eda Internacional, 2020<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Muchas escuelas en Sud\u00e1frica tienen una infraestructura y unas instalaciones sanitarias deficientes, lo que representa una serie de \u00abfallas end\u00e9micas en el sistema\u00bb (Amnist\u00eda Internacional, 2020). De hecho, en 2013, el gobierno implement\u00f3 las Normas y Est\u00e1ndares M\u00ednimos para garantizar que las escuelas tuvieran unas instalaciones sanitarias buenas y seguras para 2016, pero estos objetivos no se han cumplido. Por ejemplo, no todos los ni\u00f1os de las escuelas sudafricanas tienen acceso a inodoros y letrinas que funcionen y sean seguros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las instalaciones b\u00e1sicas tambi\u00e9n est\u00e1n mal mantenidas, a menudo fabricadas con materiales peligrosos como el amianto, que pueden tener consecuencias perjudiciales para el desarrollo de los ni\u00f1os. Las aulas est\u00e1n abarrotadas y los materiales educativos a menudo son objeto de vandalismo. Como resultado de estas condiciones, los ni\u00f1os y las ni\u00f1as no est\u00e1n aprendiendo correctamente: m\u00e1s de 3\/4 de los ni\u00f1os sudafricanos carecen de comprensi\u00f3n lectora a la edad de nueve a\u00f1os, una estad\u00edstica que es peor en ciertas provincias, como Limpopo (91%) y el Cabo Oriental (85%). De cada 100 alumnos, solo 14 tienen el nivel necesario para asistir a la educaci\u00f3n universitaria (Amnist\u00eda Internacional, 2020).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acceso a la escuela tambi\u00e9n es un problema. Aunque el Departamento de Transporte promete ofrecer transporte a la escuela para quienes viven a m\u00e1s de 3 kil\u00f3metros de distancia, algunos ni\u00f1os contin\u00faan caminando esa distancia para obtener su educaci\u00f3n. Esta distancia es peor para los ni\u00f1os que viven en grupos de bajos ingresos. Mohamed se preocupa por el impacto futuro en el crecimiento de los ni\u00f1os, tanto para ellos como para el pa\u00eds. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abEl fracaso reiterado del gobierno para abordar los problemas no es solo una cuesti\u00f3n de responsabilidad; tiene consecuencias para las oportunidades de vida de miles de j\u00f3venes y el futuro de este pa\u00eds.\u00bb <\/p>\n<cite>&#8211; Amnist\u00eda Internacional, 2020<\/cite><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.humanium.org\/es\/salud\/%20\">Derecho a la salud<\/a><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s del <em>apartheid<\/em>, Sud\u00e1frica realiz\u00f3 cambios significativos en el sector sanitario y brind\u00f3 ayuda a poblaciones a las que anteriormente se les hab\u00eda negado el acceso a los cuidados. Hoy en d\u00eda, el acceso sigue siendo precario y \u00abmiles de ni\u00f1os mueren por enfermedades tratables y evitables\u00bb (UNICEF Sud\u00e1frica, s. f.). La <a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/salud\/mortalidad-infantil\/\">mortalidad de reci\u00e9n nacidos <\/a>es alta: UNICEF informa que \u00absolo en 2018, aproximadamente 43.000 ni\u00f1os menores de cinco a\u00f1os murieron en Sud\u00e1frica, y de ellos, 12.717 eran reci\u00e9n nacidos\u00bb (UNICEF Sud\u00e1frica, s. f.). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las condiciones que conducen a estas muertes (prematuridad, complicaciones del nacimiento e infecciones neonatales) son todas prevenibles y tratables. La malnutrici\u00f3n y la obesidad tambi\u00e9n influyen en la mortalidad infantil. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abLa escasez de alimentos, la alimentaci\u00f3n poco frecuente y la falta de una dieta variada son impedimentos graves para lograr niveles saludables de <a href=\"https:\/\/www.humanium.org\/es\/derecho-alimentacion\/\">nutrici\u00f3n<\/a> infantil.\u00bb <\/p>\n<cite>&#8211; UNICEF Sud\u00e1frica, s. f.<\/cite><\/blockquote>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"518\" src=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_109846385-1024x518.jpg\" alt=\"\" class=\"wp-image-16383\" style=\"width:376px;height:190px\" srcset=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_109846385-1024x518.jpg 1024w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_109846385-300x152.jpg 300w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_109846385-768x389.jpg 768w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_109846385-1536x777.jpg 1536w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_109846385-2048x1036.jpg 2048w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_109846385-830x420.jpg 830w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_109846385-230x116.jpg 230w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_109846385-350x177.jpg 350w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_109846385-480x243.jpg 480w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Los ni\u00f1os tambi\u00e9n habitan viviendas inadecuadas y, a menudo, est\u00e1n menos urbanizados que los adultos, lo cual es un problema particularmente importante, ya que la vida rural no ofrece las mismas oportunidades que la vida urbana (UNICEF Sud\u00e1frica, s. f.). Cerca de 2 millones de ni\u00f1os (o el 9% de los ni\u00f1os de Sud\u00e1frica) residen en viviendas informales: temblores en los patios traseros, habitaciones construidas con materiales no duraderos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para los adolescentes, las<a href=\"https:\/\/www.humanium.org\/es\/ninos-sida\/\"> infecciones por VIH\/SIDA<\/a> han sido particularmente perjudiciales. M\u00e1s de un tercio de las nuevas infecciones en Sud\u00e1frica \u00abocurren entre los 15 y 24 a\u00f1os. De este grupo, la incidencia del VIH fue tres veces mayor entre las adolescentes y las mujeres j\u00f3venes que entre los varones\u00bb (UNICEF Sud\u00e1frica, s. f.). Desafortunadamente, menos de 2\/3 de los ni\u00f1os reciben tratamiento con terapia antirretroviral. Las tasas de infecciones por VIH en Sud\u00e1frica apuntan al mayor problema de SIDA en \u00c1frica.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.humanium.org\/es\/derecho-agua\/\">Derecho al agua<\/a><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Katharine Hall, investigadora principal del Instituto Infantil de la Universidad de Ciudad del Cabo, tambi\u00e9n se\u00f1ala que los ni\u00f1os<a href=\"https:\/\/www.humanium.org\/es\/derecho-agua\/\"> tienen un acceso reducido al agua<\/a>. En 2018, cerca de 6 millones de ni\u00f1os (m\u00e1s del 30% de los ni\u00f1os sudafricanos) carec\u00edan de agua potable. Tambi\u00e9n faltan unas buenas instalaciones sanitarias. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abDurante 2018, el 79% de los ni\u00f1os sudafricanos tuvieron acceso a inodoros adecuados, pero sorprendentemente 4,2 millones de ni\u00f1os todav\u00eda usan letrinas sin ventilaci\u00f3n, cubos u otras instalaciones sanitarias inadecuadas.\u00bb <\/p>\n<cite>&#8211; Jones, 2020<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Estas condiciones han empeorado con la pandemia de COVID-19, un momento en el que el acceso a agua, jab\u00f3n e instalaciones sanitarias adecuados se volvi\u00f3 vital. Las medidas de seguridad, como el distanciamiento social, no eran del todo posibles en hogares superpoblados (Jones, 2020).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.humanium.org\/es\/desnutricion-y-malnutricion\/\">Derecho a la nutrici\u00f3n<\/a><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La<a href=\"https:\/\/www.humanium.org\/es\/derecho-alimentacion\/\"> nutrici\u00f3n <\/a>es un problema importante en Sud\u00e1frica, donde m\u00e1s de la mitad de los ni\u00f1os menores de cinco a\u00f1os padecen retraso en el crecimiento. En general, casi 3 de cada 10 ni\u00f1os sufren retraso en el crecimiento, una condici\u00f3n que afecta su crecimiento y desarrollo \u00abdebido al da\u00f1o f\u00edsico y cognitivo irreversible causado por las privaciones nutricionales persistentes.\u00bb (UNICEF Sud\u00e1frica, s. f.). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La buena nutrici\u00f3n es fundamental para el bienestar de un ni\u00f1o;<a href=\"https:\/\/www.humanium.org\/es\/desnutricion-y-malnutricion\/\"> la malnutrici\u00f3n<\/a> puede conducir a la morbilidad y mortalidad infantil y fomenta el c\u00edrculo vicioso de la<a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/pobreza\/\"> pobreza<\/a>. En comparaci\u00f3n con otros pa\u00edses africanos, Sud\u00e1frica tiene la tasa m\u00e1s alta de retraso en el crecimiento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.humanium.org\/es\/derecho-identidad\/#:~:text=The%20right%20for%20each%20child,and%20nationality%20of%20the%20individual.\">Derecho a la identidad<\/a><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La secci\u00f3n 28 (1) (a) de la Constituci\u00f3n de Sud\u00e1frica establece que los ni\u00f1os tienen derecho a un nombre y a una <a href=\"https:\/\/www.humanium.org\/es\/derecho-identidad\/\">identidad.<\/a> La Ley de Registro de Nacimientos y Defunciones se ocupa del registro de los nacimientos de ni\u00f1os (UNICEF Sud\u00e1frica, s. f.). Para los<a href=\"https:\/\/www.humanium.org\/es\/migracion-infantil\/\"> ni\u00f1os migrantes indocumentados<\/a>, esto es m\u00e1s complejo: la Ley de la Infancia 38 de 2005 establece que aunque est\u00e9n <a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/aislamiento-desarraigo\/apatridas-invisibles\/\">indocumentados<\/a>, los ni\u00f1os migrantes pueden ser procesados, su identidad puede no estar registrada con actas de nacimiento sudafricanas, lo que significa que cuando cumplen 18 a\u00f1os, pueden convertirse en adultos indocumentados y, como resultado, ser deportados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Factores de riesgo \u2192 Desaf\u00edos espec\u00edficos de cada pa\u00eds<\/strong><strong><\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/explotacion\/trabajo-infantil\/\">Trabajo infantil<\/a><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El gobierno de Sud\u00e1frica ha ratificado todos los convenios internacionales clave sobre trabajo infantil. Adem\u00e1s, en 2019 Sud\u00e1frica puso en marcha el Marco de Pol\u00edticas Nacionales de Prevenci\u00f3n y Lucha contra la trata de personas. A pesar de estos esfuerzos, la Oficina de Asuntos Laborales Internacionales explica que \u00abexisten brechas que dificultan la coordinaci\u00f3n efectiva de los esfuerzos para abordar el trabajo infantil, incluida la eficacia en el cumplimiento de los mandatos\u00bb (Oficina de Asuntos Laborales Internacionales, s. f.).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como resultado, los ni\u00f1os en Sud\u00e1frica se ven involucrados en algunas de las peores formas de<a href=\"https:\/\/www.humanium.org\/es\/trabajo-infantil\/\"> trabajo infantil<\/a>, como la explotaci\u00f3n sexual comercial y la mendicidad forzada. Sud\u00e1frica es tambi\u00e9n un importante pa\u00eds de destino para la<a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/explotacion\/trata-ninos\/\"> trata infantil<\/a>; se trata con ni\u00f1os de \u00e1reas rurales pobres que se llevan a ciudades como Ciudad del Cabo, Durban y Johannesburgo. La alta<a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/pobreza\/\"> pobreza<\/a> en el pa\u00eds a menudo hace que los ni\u00f1os refugiados, hu\u00e9rfanos y con discapacidades sean vulnerables a las peores formas de trabajo infantil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s del 40% de los ni\u00f1os en Sud\u00e1frica en general son<a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/pobreza\/\"> pobres y con bajos ingresos<\/a>, y dos tercios de los ni\u00f1os en \u00e1reas rurales son pobres y tienen bajos ingresos. M\u00e1s del 50% de los ni\u00f1os de Sud\u00e1frica viven por debajo del umbral de <a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/pobreza\/\">pobreza<\/a> (UNICEF Sud\u00e1frica, s. f.).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.humanium.org\/es\/violencia\/\">Violencia<\/a><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Los ni\u00f1os sufren el pasado violento de Sud\u00e1frica, derivado tambi\u00e9n de la alta pobreza y el desempleo. Los ni\u00f1os y las ni\u00f1as necesitan m\u00e1s protecci\u00f3n a medida que el abuso y la negligencia se normalizan m\u00e1s en la vida social. UNICEF se\u00f1ala cuatro problemas importantes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En primer lugar, los ni\u00f1os se quedan sin padres<a href=\"https:\/\/www.humanium.org\/es\/ninos-sida\/\"> debido al VIH<\/a> y, en segundo lugar, Sud\u00e1frica es un destino importante para las personas refugiadas, pero sus hijos e hijas a menudo se enfrentan a la discriminaci\u00f3n. Adem\u00e1s, la<a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/discriminacion\/derechos-ninas\/\"> violencia de g\u00e9nero<\/a> es una emergencia continua, ya que las ni\u00f1as sufren numerosas formas de violencia sexual, a menudo por parte de personas de su c\u00edrculo. Finalmente, con el giro digital, los ni\u00f1os tambi\u00e9n sufren<a href=\"https:\/\/www.humanium.org\/es\/violencia-fisica-y-virtual-bullying-en-las-escuelas-un-problema-mundial-que-hay-que-abordar\/\"> ciberacoso<\/a> (UNICEF Sud\u00e1frica, s. f.). En general, los ni\u00f1os y las ni\u00f1as tienen una gran necesidad de protecci\u00f3n contra la violencia en Sud\u00e1frica.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.humanium.org\/es\/matrimonio-infantil\/\">Matrimonio infantil<\/a><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El matrimonio infantil es ilegal en Sud\u00e1frica, ya que viola las especificaciones de la Declaraci\u00f3n de Derechos de la Constituci\u00f3n, la Ley del Ni\u00f1o de 2005 y la Ley de Reconocimiento de Matrimonios Consuetudinarios 120 de 1998, en vigor desde 2000 (Mtshali, 2014). No obstante, el lenguaje utilizado en este \u00faltimo documento no protege espec\u00edficamente a las ni\u00f1as, que no pueden dar su consentimiento si sus padres est\u00e1n de acuerdo en su nombre. Como tal, el <a href=\"https:\/\/www.humanium.org\/es\/matrimonio-infantil\/\">matrimonio infantil<\/a> forzado en Sud\u00e1frica se practica bajo el pretexto del matrimonio consuetudinario, principalmente por los zul\u00faes y los bapedi (Mtshali, 2014).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas pr\u00e1cticas se consideran culturalmente aceptables, pero son muy peligrosas para el desarrollo mental y f\u00edsico de las ni\u00f1as, ya que las privan de su derecho humano fundamental a una infancia segura, saludable y protegida.<a href=\"https:\/\/www.humanium.org\/es\/africa\/\"> \u00c1frica subsahariana y meridional<\/a> tienen altas tasas de matrimonio infantil; solo en Sud\u00e1frica, el 6% de las ni\u00f1as se casan antes de los 18 a\u00f1os (Grobler, 2019). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">James Elder, Jefe de Comunicaci\u00f3n de UNICEF de \u00c1frica oriental y meridional, advierte que la cifra puede ser mayor, ya que muchos casos de matrimonio infantil no se declaran. La directora ejecutiva de UNICEF, Henrietta Fore, lo describe mejor: \u00abel matrimonio roba la infancia\u00bb (Grobler, 2019). <a href=\"https:\/\/www.humanium.org\/es\/matrimonio-infantil\/\">El matrimonio infantil<\/a> priva a los ni\u00f1os de su infancia, felicidad y oportunidades (Grobler, 2019).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/discriminacion\/derechos-nino-lgbtq\/\">Discriminaci\u00f3n contra la infancia LGBTQ<\/a><\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" src=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_458363815-1024x680.jpg\" alt=\"\" class=\"wp-image-16384\" style=\"width:359px;height:238px\" srcset=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_458363815-1024x680.jpg 1024w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_458363815-300x199.jpg 300w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_458363815-768x510.jpg 768w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_458363815-1536x1020.jpg 1536w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_458363815-2048x1360.jpg 2048w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_458363815-830x551.jpg 830w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_458363815-230x153.jpg 230w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_458363815-350x232.jpg 350w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_458363815-480x319.jpg 480w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_458363815-272x182.jpg 272w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Sud\u00e1frica es el \u00fanico pa\u00eds en <a href=\"https:\/\/www.humanium.org\/es\/africa\/\">\u00c1frica <\/a>donde el matrimonio entre personas del mismo sexo es legal y fue el quinto pa\u00eds del mundo en prohibir la <a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/discriminacion\/\">discriminaci\u00f3n <\/a>basada en la orientaci\u00f3n sexual. Adem\u00e1s, la Declaraci\u00f3n de Derechos proh\u00edbe la discriminaci\u00f3n por motivos de orientaci\u00f3n sexual, \u00abprometiendo la plena ciudadan\u00eda a una generaci\u00f3n de j\u00f3venes LGBTI posterior al <em>apartheid<\/em>\u00bb (Smaak y Varia, 2015). Adem\u00e1s, Sud\u00e1frica tiene una estaci\u00f3n de radio gay, Gay SA Radio, que ayuda a romper los estereotipos y da voz a quienes luchan por aceptarse a s\u00ed mismos. Es una forma de dar visibilidad a la juventud LGBTIQ (Hird, 2021). No obstante, los<a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/discriminacion\/derechos-nino-lgbtq\/\"> ni\u00f1os y ni\u00f1as LGBTIQ<\/a> est\u00e1n expuestos a una homofobia continua en todas partes de la sociedad, y los gobiernos no han abordado esta discriminaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Escrito por Leah Benque<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Traducido por Cristina Morillo Berral<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Revisado por In\u00e9s M\u00aa Campillo Pazos<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>\u00daltima actualizaci\u00f3n el 4 de agosto de 2021<\/strong><\/em><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Referencias:<\/h4>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.amnesty.org\/en\/latest\/news\/2020\/02\/south-africa-broken-and-unequal-education-perpetuating-poverty-and-inequality\/\" target=\"_blank\" rel=\"noreferrer noopener\">Amnesty International (February 2020), \u201cSouth Africa: Broken and unequal education perpetuating poverty and inequality,\u201d retrieved from Amnesty International News, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/amnesty.org.za\/wp-content\/uploads\/2020\/02\/FINALBrokenAndUnequal_FULLREPORTredu_compressed.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Amnesty International (2020), \u201cBroken and Unequal: The State of Education In South Africa,\u201d retrieved from Amnesty International Reports, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.dol.gov\/agencies\/ilab\/resources\/reports\/child-labor\/south-africa\" target=\"_blank\" rel=\"noreferrer noopener\">Bureau of International Labor Affairs (n.d.), \u201cChild Labor and Forced Labor Reports &#8211; South Africa,\u201d retrieved from U.S. Department of Labor, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.childlinesa.org.za\/children\/for-children\/know-your-rights\/\" target=\"_blank\" rel=\"noreferrer noopener\">Childline USA (n.d.), \u201cKnow Your Rights,\u201d retrieved from Childline USA South Africa, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.concourt.org.za\/index.php\/children-s-rights\" target=\"_blank\" rel=\"noreferrer noopener\">Constitutional Court of South Africa (n.d.), \u201cChildren\u2019s Rights,\u201d retrieved from Constitutional Court of South Africa, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.news24.com\/news24\/SouthAfrica\/News\/hold-for-sun-am-shock-stats-22-underaged-children-get-married-every-minute-highest-percentage-in-africa-20190607\" target=\"_blank\" rel=\"noreferrer noopener\">Grobler, Riaan (June 2019), \u201c \u2018Overwhelming\u2019 stats: 22 underaged children get married every minute, highest prevalence in Africa,\u201d retrieved from News24, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.rfi.fr\/en\/africa\/20210518-being-lgbtiq-in-south-africa-and-senegal-one-continent-worlds-apart-cameroon-transgender-gay-lesbian-homosexuality\" target=\"_blank\" rel=\"noreferrer noopener\">Hird, Alison (May 2021), \u201cBeing LGBTIQ in South Africa and Senegal: one continent, worlds apart,\u201d retrieved from RFI, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/mg.co.za\/opinion\/2020-07-17-mandela-would-be-disturbed-at-statistics-showing-how-some-south-african-children-live\/\" target=\"_blank\" rel=\"noreferrer noopener\">Jones, Chris, (July 2020), \u201cMandela would be disturbed at statistics showing how some South African children live,\u201d retrieved from Mail Guardian Opinion, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/localhistories.org\/a-brief-history-of-south-africa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lambert, Tim (2020), \u201cA Brief History of South Africa,\u201d retrieved from Local Histories, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Mosikatsana, Tshepo L. (1998), \u201cChildren&#8217;s Rights and Family Autonomy in the South African Context: A Comment on Children&#8217;s Rights Under the Final Constitution,\u201d retrieved from Michigan Journal of Race and Law, Volume 3, accessed on 1 August 2021.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/journals.co.za\/doi\/10.10520\/EJC161326\" target=\"_blank\" rel=\"noreferrer noopener\">Mtshali, Velani (January 2014), \u201cForced child marriage practiced under the pretext of customary marriage in South Africa,\u201d retrieved from Sabinet African Journals, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.atlanticphilanthropies.org\/wp-content\/uploads\/2015\/09\/Out_of_the_box_queer_youth_in_South_Africa_Today_0.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Nell, Marian, and Shapiro, Janet, (July 2011), \u201cOUT OF THE BOX: Queer youth in South Africa today,\u201d retrieved from Atlantic Philanthropies, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.savethechildren.org.za\/what-we-do\/our-work\/childrens-rights\" target=\"_blank\" rel=\"noreferrer noopener\">Save the Children (n.d.), \u201cChildren\u2019s Rights,\u201d retrieved from Save the Children Organization, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.hrw.org\/news\/2015\/12\/09\/ending-child-marriage-africa\" target=\"_blank\" rel=\"noreferrer noopener\">Smaak, Annerieke, and Varia, Nisha (December 2015), \u201cEnding Child Marriage in Africa &#8211; Opening the Door for Girls\u2019 Education, Health, and Freedom from Violence,\u201d retrieved from Human Rights Watch (HRW), accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/data.worldbank.org\/country\/south-africa\" target=\"_blank\" rel=\"noreferrer noopener\">The World Bank (2020), \u201cSouth Africa,\u201d retrieved from The World Bank Data, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.unicef.org\/southafrica\/media\/4241\/file\/ZAF-multidimensional-child-poverty-analysis-policy-brief-07July-2020.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">UNICEF South Africa (July 2020), \u201cChild poverty in South Africa,\u201d retrieved from UNICEF South Africa, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.unicef.org\/southafrica\/child-protection\" target=\"_blank\" rel=\"noreferrer noopener\">UNICEF South Africa (n.d.), \u201cChild protection &#8211; UNICEF is committed to ensuring a safe and inclusive environment for every child,\u201d retrieved from UNICEF Organization, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.unicef.org\/southafrica\/education\" target=\"_blank\" rel=\"noreferrer noopener\">UNICEF South Africa (n.d.), \u201cEducation &#8211; UNICEF is committed to ensuring quality learning for every child,\u201d retrieved from UNICEF Organization, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.unicef.org\/southafrica\/health\" target=\"_blank\" rel=\"noreferrer noopener\">UNICEF South Africa (n.d.), \u201cHealth &#8211; UNICEF is committed to ensuring that every child survives and thrives,\u201d retrieved from UNICEF Organization, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.unicef.org\/southafrica\/what-we-do\" target=\"_blank\" rel=\"noreferrer noopener\">UNICEF South Africa (n.d.), \u201cWhat we do,\u201d retrieved from UNICEF Organization, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.unicef.org\/southafrica\/media\/4036\/file\/ZAF-Nutrition-brief-2020.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">UNICEF South Africa (July 2020), \u201cSouth Africa Nutrition Brief,\u201d retrieved from UNICEF South Africa, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.unicef.org\/southafrica\/media\/5316\/file\/ZAF-COVID-19-situation-report-17-7-July-2021.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">UNICEF South Africa (June 2021), \u201cSOUTH AFRICA COVID-19 &#8211; Situation Report No.17,\u201d retrieved from UNICEF South Africa, accessed on 1 August 2021.<\/a><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Western Cape Government (2019) \u201cChildren, know your rights and responsibilities,\u201d retrieved from Western Cape Government, accessed on 1 August 2021.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><a href=\"#_ftnref1\"><sup>[1]<\/sup><\/a> Este art\u00edculo de ninguna manera pretende dar una descripci\u00f3n completa o representativa de los derechos del ni\u00f1o en Sud\u00e1frica; de hecho, uno de los muchos desaf\u00edos es la escasa informaci\u00f3n actualizada sobre los ni\u00f1os de Sud\u00e1frica, gran parte de la cual no es confiable, no es representativa, est\u00e1 desactualizada o simplemente no existe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descubriendo los Derechos del Ni\u00f1o en Sud\u00e1frica Sud\u00e1frica ratific\u00f3 la Convenci\u00f3n sobre los Derechos del Ni\u00f1o en junio de 1995. Un a\u00f1o despu\u00e9s, el gobierno sudafricano especific\u00f3 los derechos de los ni\u00f1os en la Declaraci\u00f3n de Derechos de la Constituci\u00f3n, secci\u00f3n 28: \u00abtodo ni\u00f1o tiene derecho a una nutrici\u00f3n b\u00e1sica, refugio, atenci\u00f3n m\u00e9dica y servicios [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-1830","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ni\u00f1os de Sud\u00e1frica - Humanium<\/title>\n<meta name=\"description\" content=\"Los ni\u00f1os de Sud\u00e1frica nacen en desigualdad de oportunidades; afectados por la pobreza, la mala salud y un dif\u00edcil acceso a la educaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.humanium.org\/es\/sudafrica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ni\u00f1os de Sud\u00e1frica - Humanium\" \/>\n<meta property=\"og:description\" content=\"Los ni\u00f1os de Sud\u00e1frica nacen en desigualdad de oportunidades; afectados por la pobreza, la mala salud y un dif\u00edcil acceso a la educaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.humanium.org\/es\/sudafrica\/\" \/>\n<meta property=\"og:site_name\" content=\"Humanium\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-13T21:05:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1786480814.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/sudafrica\\\/\",\"url\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/sudafrica\\\/\",\"name\":\"Ni\u00f1os de Sud\u00e1frica - Humanium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/sudafrica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/sudafrica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/shutterstock_1786480814.jpg\",\"datePublished\":\"2016-01-22T08:48:18+00:00\",\"dateModified\":\"2025-12-13T21:05:32+00:00\",\"description\":\"Los ni\u00f1os de Sud\u00e1frica nacen en desigualdad de oportunidades; afectados por la pobreza, la mala salud y un dif\u00edcil acceso a la educaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/sudafrica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.humanium.org\\\/es\\\/sudafrica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/sudafrica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/shutterstock_1786480814.jpg\",\"contentUrl\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/shutterstock_1786480814.jpg\",\"width\":200,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/sudafrica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ni\u00f1os de Sud\u00e1frica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/\",\"name\":\"Humanium\",\"description\":\"\u00a1Los ni\u00f1os primero!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ni\u00f1os de Sud\u00e1frica - Humanium","description":"Los ni\u00f1os de Sud\u00e1frica nacen en desigualdad de oportunidades; afectados por la pobreza, la mala salud y un dif\u00edcil acceso a la educaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.humanium.org\/es\/sudafrica\/","og_locale":"es_ES","og_type":"article","og_title":"Ni\u00f1os de Sud\u00e1frica - Humanium","og_description":"Los ni\u00f1os de Sud\u00e1frica nacen en desigualdad de oportunidades; afectados por la pobreza, la mala salud y un dif\u00edcil acceso a la educaci\u00f3n.","og_url":"https:\/\/www.humanium.org\/es\/sudafrica\/","og_site_name":"Humanium","article_modified_time":"2025-12-13T21:05:32+00:00","og_image":[{"width":200,"height":200,"url":"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1786480814.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.humanium.org\/es\/sudafrica\/","url":"https:\/\/www.humanium.org\/es\/sudafrica\/","name":"Ni\u00f1os de Sud\u00e1frica - Humanium","isPartOf":{"@id":"https:\/\/www.humanium.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.humanium.org\/es\/sudafrica\/#primaryimage"},"image":{"@id":"https:\/\/www.humanium.org\/es\/sudafrica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1786480814.jpg","datePublished":"2016-01-22T08:48:18+00:00","dateModified":"2025-12-13T21:05:32+00:00","description":"Los ni\u00f1os de Sud\u00e1frica nacen en desigualdad de oportunidades; afectados por la pobreza, la mala salud y un dif\u00edcil acceso a la educaci\u00f3n.","breadcrumb":{"@id":"https:\/\/www.humanium.org\/es\/sudafrica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.humanium.org\/es\/sudafrica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.humanium.org\/es\/sudafrica\/#primaryimage","url":"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1786480814.jpg","contentUrl":"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2021\/11\/shutterstock_1786480814.jpg","width":200,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.humanium.org\/es\/sudafrica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.humanium.org\/es\/"},{"@type":"ListItem","position":2,"name":"Ni\u00f1os de Sud\u00e1frica"}]},{"@type":"WebSite","@id":"https:\/\/www.humanium.org\/es\/#website","url":"https:\/\/www.humanium.org\/es\/","name":"Humanium","description":"\u00a1Los ni\u00f1os primero!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.humanium.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/pages\/1830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/comments?post=1830"}],"version-history":[{"count":18,"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/pages\/1830\/revisions"}],"predecessor-version":[{"id":21034,"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/pages\/1830\/revisions\/21034"}],"wp:attachment":[{"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/media?parent=1830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}