{"id":479,"date":"2012-12-05T10:40:34","date_gmt":"2012-12-05T10:40:34","guid":{"rendered":"http:\/\/www.humanium.org\/es\/?page_id=479"},"modified":"2026-08-20T17:24:39","modified_gmt":"2026-08-20T17:24:39","slug":"mortalidad-infantil","status":"publish","type":"page","link":"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/salud\/mortalidad-infantil\/","title":{"rendered":"Mortalidad infantil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Gracias a algunos esfuerzos notables por garantizar la supervivencia infantil sostenible, el mundo ha reconocido y avanzado hacia el pleno disfrute del <\/strong><a href=\"https:\/\/www.humanium.org\/es\/derecho-vida\/?gad_source=1&amp;gclid=CjwKCAiAq4KuBhA6EiwArMAw1HT8CC-SgFSkgUibahdbXPej-jzZMQ9kZqpvSjfJu3Rqj-GBPI2mGBoCfcsQAvD_BwE\"><strong>derecho a la vida de todo ni\u00f1o<\/strong><\/a><strong>. Sin embargo, en 2021, cinco millones de ni\u00f1os no llegaron a cumplir los cinco a\u00f1os a nivel mundial, por tanto, a\u00fan quedan desaf\u00edos pendientes en lo que respecta a la supervivencia infantil. Por desgracia, 2,3 millones de ni\u00f1os sucumben en su primer mes de vida y 2,7 millones de ni\u00f1os mueren antes de cumplir los cinco a\u00f1os, especialmente, en <\/strong><a href=\"https:\/\/www.humanium.org\/es\/africa\/\"><strong>\u00c1frica subsahariana<\/strong><\/a><strong> y en<\/strong><a href=\"https:\/\/www.humanium.org\/es\/asia-pacifico\/\"><strong> Asia<\/strong><\/a><strong> meridional<\/strong><strong>. Estas duras cifras ponen de relieve el enorme impacto que conllevan las desigualdades geogr\u00e1ficas y econ\u00f3micas, lo que supone una grave amenaza para conseguir cumplir con el objetivo <\/strong><a href=\"https:\/\/www.humanium.org\/es\/como-puede-el-ods-4-mejorar-el-derecho-del-nino-a-la-educacion\/\"><strong>ODS<\/strong><\/a><strong> 3.2 sobre mortalidad de menores de cinco a\u00f1os para 2030.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"540\" src=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2416028877-1024x540.jpg\" alt=\"\" class=\"wp-image-19051\" srcset=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2416028877-1024x540.jpg 1024w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2416028877-300x158.jpg 300w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2416028877-768x405.jpg 768w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2416028877-1536x810.jpg 1536w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2416028877-2048x1080.jpg 2048w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2416028877-830x438.jpg 830w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2416028877-230x121.jpg 230w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2416028877-350x185.jpg 350w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2416028877-480x253.jpg 480w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Mortalidad neonatal<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La tasa de mortalidad <a href=\"https:\/\/www.humanium.org\/es\/un-recien-nacido-llega-a-nuestro-mundo\/\">neonatal<\/a> hace referencia a la probabilidad de que un reci\u00e9n nacido muera durante sus primeros 28 d\u00edas de vida por cada 1000 nacidos vivos (Mortalidad neonatal, UNICEF, 2023). Los 28 primeros d\u00edas de vida \u2014el per\u00edodo neonatal\u2014 es el per\u00edodo m\u00e1s vulnerable para la supervivencia de un ni\u00f1o. En comparaci\u00f3n, la probabilidad de que un beb\u00e9 muriese despu\u00e9s del primer mes y antes de alcanzar el primer a\u00f1o de vida se estimaba en 11 por cada 1000 nacidos vivos. Por otro lado, la probabilidad de que un ni\u00f1o muriese despu\u00e9s de cumplir el a\u00f1o y antes de alcanzar los cinco a\u00f1os se estimaba en 10 por cada 1000 nacidos vivos en 2021 (<em>Informe sobre mortalidad infantil<\/em>, 2022).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A nivel mundial, 2,3 millones de ni\u00f1os murieron en su primer mes de vida en 2021 (aproximadamente 6400 muertes neonatales por d\u00eda). A pesar de que la tasa de mortalidad neonatal ha descendido globalmente (la tasa media global baj\u00f3 un 51 %, se pas\u00f3 de 37 beb\u00e9s muertos por cada 1000 nacidos vivos en 1990 a 18 en 2021), existe una marcada disparidad entre regiones y pa\u00edses en lo que se refiere a la mortalidad neonatal. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A escala regional, la mortalidad <a href=\"https:\/\/www.humanium.org\/es\/un-recien-nacido-llega-a-nuestro-mundo\/\">neonatal<\/a> m\u00e1s alta se encuentra en <a href=\"https:\/\/www.humanium.org\/es\/africa\/\">\u00c1frica<\/a> subsahariana y en <a href=\"https:\/\/www.humanium.org\/es\/asia-pacifico\/\">Asia<\/a> meridional, con una tasa de mortalidad neonatal estimada en 27 y 23 beb\u00e9s muertos por cada 1000 nacidos vivos, respectivamente, en 2021. Un ni\u00f1o nacido en <a href=\"https:\/\/www.humanium.org\/es\/africa\/\">\u00c1frica<\/a> subsahariana ten\u00eda cerca de diez veces m\u00e1s probabilidades de fallecer en su primer mes de vida que un ni\u00f1o nacido en un pa\u00eds de ingresos altos, mientras que un ni\u00f1o nacido en Asia meridional ten\u00eda nueve veces m\u00e1s probabilidades de morir (<em>Informe sobre mortalidad infantil<\/em>, 2022).&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Mortalidad de menores de cinco a\u00f1os<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La tasa de mortalidad de menores de cinco a\u00f1os hace referencia a la probabilidad de que un reci\u00e9n nacido muera antes de cumplir los cinco a\u00f1os por cada 1000 ni\u00f1os nacidos vivos (Informe sobre mortalidad infantil, 2022). En 2021, cinco millones de ni\u00f1os menores de cinco a\u00f1os murieron (UNICEF, <em>Mortalidad de menores de cinco a\u00f1os<\/em>, 2023). Alrededor de la mitad de estas muertes (2,7 millones) se produjeron en ni\u00f1os de entre 1 y 59 meses de edad, mientras que el resto de las defunciones (2,3 millones) ocurrieron en beb\u00e9s de solamente un mes de vida (<em>Informe sobre mortalidad infantil<\/em>, 2022).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Existe una mayor probabilidad de que los ni\u00f1os nacidos en pa\u00edses de ingresos bajos mueran antes de cumplir los cinco a\u00f1os. Seg\u00fan los datos sobre mortalidad infantil de 2021, los ni\u00f1os nacidos en pa\u00edses de ingresos bajos ten\u00edan catorce veces m\u00e1s probabilidades de morir antes de cumplir los cinco a\u00f1os que aquellos ni\u00f1os nacidos en pa\u00edses de ingresos altos (Child Mortality Report, 2022).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las \u00faltimas tres d\u00e9cadas ha habido un enorme progreso a nivel mundial en lo que respecta a la supervivencia infantil. La tasa mundial de mortalidad de menores de cinco a\u00f1os ha descendido un 59 %, se ha pasado de 93 ni\u00f1os muertos por cada 1000 nacidos vivos en 1990 a 38 en 2021. Adem\u00e1s, el progreso para reducir las tasas de mortalidad infantil ha aumentado en la d\u00e9cada de los 2000 en comparaci\u00f3n con la d\u00e9cada de los 90; la tasa anual de reducci\u00f3n de la tasa de mortalidad de menores de cinco a\u00f1os ha pasado del 1,8 % en la d\u00e9cada de los 90 al 4 % entre 2000 y 2009 y al 2,7 % entre 2010 y 2021 (UNICEF, <em>Mortalidad de menores de cinco a\u00f1os<\/em>, 2023).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde 1990, la mayor\u00eda de las regiones del mundo y 162 de 200 pa\u00edses han reducido al menos a la mitad sus tasas de mortalidad de menores de cinco a\u00f1os. En ese mismo per\u00edodo, la mortalidad de menores de cinco a\u00f1os ha descendido a al menos dos tercios en el 42 % (92 pa\u00edses) de los 200 pa\u00edses. 39 de estos pa\u00edses son pa\u00edses de bajos o medianos ingresos, lo que demuestra que es posible mejorar la supervivencia infantil incluso en lugares con menos recursos, aunque el peso de la mortalidad infantil se encuentre distribuido de manera desigual por el mundo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Mortalidad entre ni\u00f1os, adolescentes y j\u00f3venes (5-24 a\u00f1os)<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cerca de un mill\u00f3n de adolescentes murieron en 2021 y, a nivel mundial, alrededor del 43 % de las defunciones de personas entre los 5 y 24 a\u00f1os se produjeron en adolescentes. En todas las regiones, la probabilidad de morir entre los 5 y 24 a\u00f1os es inferior a la de menores de cinco a\u00f1os. En 2021, con 17 muertes por cada 1000 ni\u00f1os de cinco a\u00f1os, la probabilidad de morir entre ni\u00f1os y j\u00f3venes de 5 a 24 a\u00f1os representaba aproximadamente la mitad de la tasa de mortalidad mundial de menores de cinco a\u00f1os, pese a que la exposici\u00f3n al riesgo de muerte es cuatro veces mayor en el grupo de mayor edad (<em>Informe sobre mortalidad infantil<\/em>, 2022).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde 1990 hasta 2021, la tasa de mortalidad de ni\u00f1os y j\u00f3venes de 5 a 24 a\u00f1os se redujo un 46 %, de 31 a 17 muertes por cada 1.000 ni\u00f1os de 5 a\u00f1os, mientras que la mortalidad de los adolescentes disminuy\u00f3 un 43 %, durante el mismo per\u00edodo, de 13 a 7 muertes por cada 1.000 adolescentes de 10 a\u00f1os (<em>Datos de mortalidad de ni\u00f1os y j\u00f3venes entre 5 y 24 a\u00f1os<\/em>, UNICEF, 2023).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las probabilidades de supervivencia de ni\u00f1os, adolescentes y j\u00f3venes de entre 5 y 24 a\u00f1os var\u00edan considerablemente seg\u00fan la regi\u00f3n y el pa\u00eds. <a href=\"https:\/\/www.humanium.org\/es\/africa\/\">\u00c1frica<\/a> subsahariana y <a href=\"https:\/\/www.humanium.org\/es\/asia-pacifico\/\">Asia<\/a> central y meridional confirman su tendencia negativa tambi\u00e9n en esta materia. Por ejemplo, alrededor del 70 % de todas las muertes entre personas de 5 a 24 a\u00f1os se produjeron en <a href=\"https:\/\/www.humanium.org\/es\/africa\/\">\u00c1frica<\/a> subsahariana (46 %) y en Asia central y meridional (24 %). Si se mantienen las tendencias actuales, se estima que cerca de 19 millones de ni\u00f1os, adolescentes y j\u00f3venes de entre 5 y 24 a\u00f1os morir\u00e1n entre 2022 y 2030 y que m\u00e1s de un 70 % de esas muertes ocurrir\u00e1n \u00fanicamente en dichas regiones (<em>Informe sobre mortalidad infantil<\/em>, 2022).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Causas de la mortalidad infantil<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La mayor\u00eda de las muertes neonatales (75 %) se producen en la primera semana de vida del beb\u00e9 y, en 2019, alrededor de un mill\u00f3n de reci\u00e9n nacidos murieron en las primeras 24 horas de vida. Los partos prematuros, las complicaciones relacionadas con el parto (asfixia o falta de respiraci\u00f3n al nacer), las infecciones y las anomal\u00edas cong\u00e9nitas provocaron la mayor\u00eda de las muertes neonatales en 2019. Desde que finaliza el per\u00edodo neonatal y a lo largo de los cinco primeros a\u00f1os de vida, las principales causas de muerte son la neumon\u00eda, la diarrea, las anomal\u00edas cong\u00e9nitas y la malaria (<em>Mortalidad de los reci\u00e9n nacidos<\/em>, OMS, 2022).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los ni\u00f1os desnutridos, especialmente aquellos que padecen desnutrici\u00f3n aguda severa, corren un mayor riesgo de morir por enfermedades infantiles comunes tales como la diarrea, la neumon\u00eda y la malaria. Los <a href=\"https:\/\/www.humanium.org\/es\/desnutricion-y-malnutricion\/\">factores relativos a la nutrici\u00f3n<\/a> causan cerca del 45 % de las muertes de ni\u00f1os menores de cinco a\u00f1os (<em>Mortalidad de menores de cinco a\u00f1os<\/em>, OMS, 2022).<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2414742463-1024x683.jpg\" alt=\"\" class=\"wp-image-19041\" style=\"width:343px;height:auto\" srcset=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2414742463-1024x683.jpg 1024w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2414742463-300x200.jpg 300w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2414742463-768x512.jpg 768w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2414742463-1536x1024.jpg 1536w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2414742463-2048x1365.jpg 2048w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2414742463-830x553.jpg 830w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2414742463-230x153.jpg 230w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2414742463-350x233.jpg 350w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2414742463-480x320.jpg 480w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2414742463-272x182.jpg 272w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Los <a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/violencia\/ninos-guerra\/\">conflictos b\u00e9licos<\/a> y la <a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/ambiente\/emergencia-climatica\/#:~:text=Esta%20emergencia%20es%20el%20reflejo,desplazamiento%20humano%20forzado%20en%20masa.\">emergencia clim\u00e1tica<\/a> \u2014incluyendo la pandemia de la COVID-19\u2014 contin\u00faan siendo una amenaza para la supervivencia infantil. La tasa de mortalidad de menores de cinco a\u00f1os en los 37 pa\u00edses clasificados como fr\u00e1giles y afectados por el <a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/violencia\/ninos-guerra\/\">conflicto<\/a> triplic\u00f3 la tasa del resto de pa\u00edses. Si bien los datos disponibles sobre el impacto de la COVID-19 no muestran evidencias sistem\u00e1ticas de un exceso de mortalidad infantil, es necesario realizar un seguimiento continuado de este problema dada la informaci\u00f3n limitada existente y el impacto potencial de la pandemia en el acceso a la atenci\u00f3n sanitaria y a la prestaci\u00f3n de servicios (<em>Informe sobre mortalidad infantil<\/em>, 2022).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al desaparecer las enfermedades infecciosas propias de la infancia, surgen nuevos peligros que se convierten en las primeras causas de muerte y discapacidades de por vida entre los ni\u00f1os de entre 5 y 14 a\u00f1os: los accidentes y traumatismos (incluyendo las lesiones por accidentes de tr\u00e1fico, los ahogamientos, las quemaduras y las ca\u00eddas), las conductas autolesivas y la violencia interpersonal (<em>Mortalidad entre los ni\u00f1os de 5 a 14 a\u00f1os<\/em>, OMS, 2019). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos patrones de muerte de los ni\u00f1os m\u00e1s mayores y de los adolescentes j\u00f3venes reflejan los perfiles de riesgo subyacentes de los grupos de edad. Las <a href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/discriminacion\/derechos-ninas\/\">diferencias en funci\u00f3n del sexo<\/a> en las tasas de mortalidad se hacen evidentes en la adolescencia con tasas de muerte m\u00e1s elevadas entre los chicos que se enfrentan a las condiciones mencionadas anteriormente, as\u00ed como tambi\u00e9n a la violencia colectiva y a la intervenci\u00f3n policial (<em>Adolescente mayor<\/em>, OMS, 2022).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Desigualdades geogr\u00e1ficas y econ\u00f3micas como causas de la mortalidad infantil<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los obst\u00e1culos m\u00e1s notables a los que se siguen enfrentando los ni\u00f1os son las desigualdades generalizadas a nivel regional y econ\u00f3mico, que afectan a su supervivencia. Los datos indican que m\u00e1s del 80 % de las muertes infantiles se producen en solo dos regiones: \u00c1frica subsahariana y Asia meridional. <a href=\"https:\/\/www.humanium.org\/es\/africa\/\">\u00c1frica<\/a> subsahariana contin\u00faa siendo la regi\u00f3n con la tasa m\u00e1s alta de mortalidad de menores de cinco a\u00f1os (73 ni\u00f1os muertos por cada 1000 nacidos vivos).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2021, uno de cada catorce ni\u00f1os de <a href=\"https:\/\/www.humanium.org\/es\/africa\/\">\u00c1frica<\/a> subsahariana muri\u00f3 antes de cumplir los cinco a\u00f1os \u2014el riesgo de muerte es 15 veces mayor que en el caso de los ni\u00f1os nacidos en pa\u00edses de ingresos altos y, adem\u00e1s, esta regi\u00f3n lleva 20 a\u00f1os de retraso en comparaci\u00f3n con la media mundial, pues esa misma tasa de uno de cada catorce ni\u00f1os ya se alcanz\u00f3 en 2001. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La subregi\u00f3n de <a href=\"https:\/\/www.humanium.org\/es\/asia-pacifico\/\">Asia<\/a> meridional sufri\u00f3 1,3 millones de muertes de menores de cinco a\u00f1os en 2021 (alrededor del 26 % del total mundial frente al 27 % de ni\u00f1os nacidos vivos en 2021). La subregi\u00f3n de Asia meridional registr\u00f3 el 98 % de muertes de menores de cinco a\u00f1os de la regi\u00f3n de Asia central y meridional en 2021 (<em>Informe sobre mortalidad infantil<\/em>, 2022).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, los ni\u00f1os que viven en zonas fr\u00e1giles y afectadas por el conflicto son especialmente vulnerables. Con 75 ni\u00f1os muertos por cada 1000 nacidos vivos en 2021, la tasa de mortalidad de menores de cinco a\u00f1os en los 37 pa\u00edses clasificados como fr\u00e1giles y afectados por el conflicto era tres veces m\u00e1s elevada que en el resto de los pa\u00edses (<em>Informe sobre mortalidad infantil<\/em>, 2022).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Supervivencia infantil y Objetivos de Desarrollo Sostenible (ODS)<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El <a href=\"https:\/\/www.humanium.org\/es\/como-puede-el-ods-4-mejorar-el-derecho-del-nino-a-la-educacion\/\">objetivo<\/a> ODS 3.2 sobre la mortalidad infantil tiene como finalidad erradicar, para 2030, las muertes evitables de reci\u00e9n nacidos y menores de cinco a\u00f1os. Todos los pa\u00edses tienen como objetivo reducir la mortalidad neonatal a al menos 12 por cada 1000 nacidos vivos, as\u00ed como tambi\u00e9n bajar la mortalidad de menores de cinco a\u00f1os a al menos 25 por cada 1000 nacidos vivos (OMS, 2023).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las desigualdades geogr\u00e1ficas y econ\u00f3micas que contribuyen al riesgo de muerte infantil representan una amenaza para el logro de los ODS a nivel global (<em>Informe sobre mortalidad infantil<\/em>, 2022). En m\u00e1s de un cuarto de todos los pa\u00edses, es necesario actuar con urgencia para acelerar la reducci\u00f3n de la mortalidad infantil y, as\u00ed, alcanzar los objetivos <a href=\"https:\/\/www.humanium.org\/es\/como-puede-el-ods-4-mejorar-el-derecho-del-nino-a-la-educacion\/\">ODS<\/a> relativos a la erradicaci\u00f3n de las muertes evitables de ni\u00f1os para 2030. De los 200 pa\u00edses analizados, 133 han alcanzado ya el objetivo ODS sobre la mortalidad de menores de cinco a\u00f1os, y se espera que 13 pa\u00edses cumplan este objetivo para 2030 si la tendencia actual se mantiene.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es necesario que aumenten los esfuerzos para agilizar el progreso en los 54 pa\u00edses restantes (casi tres cuartas partes se encuentran en la regi\u00f3n de \u00c1frica subsahariana) con el fin de alcanzar el objetivo ODS relativo a la mortalidad de menores de cinco a\u00f1os para 2030. De estos 54 pa\u00edses, 37 necesitar\u00e1n duplicar con creces su tasa actual de progreso o invertir una tendencia reciente al alza para cumplir con el objetivo ODS para 2030 (<em>Supervivencia infantil y los ODS<\/em>, UNICEF, 2023).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incluso m\u00e1s pa\u00edses corren el riesgo de no cumplir con el objetivo <a href=\"https:\/\/www.humanium.org\/es\/como-puede-el-ods-4-mejorar-el-derecho-del-nino-a-la-educacion\/\">ODS<\/a> sobre la mortalidad neonatal que con el objetivo sobre la mortalidad de menores de cinco a\u00f1os. En las tendencias actuales, 63 pa\u00edses tendr\u00e1n que acelerar su progreso para alcanzar el objetivo relativo a la mortalidad neonatal para 2030, mientras que 55 pa\u00edses tendr\u00e1n que duplicar con creces su tasa actual a la baja o invertir una tendencia reciente al alza para cumplir con el objetivo a tiempo (<em>Supervivencia infantil y los ODS<\/em>, UNICEF, 2023).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al cumplir a tiempo con el objetivo <a href=\"https:\/\/www.humanium.org\/es\/como-puede-el-ods-4-mejorar-el-derecho-del-nino-a-la-educacion\/\">ODS<\/a> sobre mortalidad de menores de cinco a\u00f1os en aquellos pa\u00edses en riesgo de no alcanzarlo, se evitar\u00edan casi 10 millones de defunciones de menores de cinco a\u00f1os en comparaci\u00f3n con las tendencias actuales. Si se mantienen las tendencias de ahora, alrededor de 40 millones de menores de cinco a\u00f1os morir\u00e1n antes de 2030, siendo la mitad reci\u00e9n nacidos. M\u00e1s de la mitad de estas muertes (59 %) se producir\u00e1n en <a href=\"https:\/\/www.humanium.org\/es\/africa\/\">\u00c1frica<\/a> subsahariana (24 millones) y otro 24 % en <a href=\"https:\/\/www.humanium.org\/es\/asia-pacifico\/\">Asia<\/a> meridional (9 millones) (<em>Supervivencia infantil y los ODS<\/em>, UNICEF, 2023).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Posibles soluciones para garantizar la supervivencia infantil sostenible<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2271021543-1024x683.jpg\" alt=\"\" class=\"wp-image-19042\" srcset=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2271021543-1024x683.jpg 1024w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2271021543-300x200.jpg 300w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2271021543-768x512.jpg 768w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2271021543-1536x1024.jpg 1536w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2271021543-2048x1365.jpg 2048w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2271021543-830x553.jpg 830w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2271021543-230x153.jpg 230w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2271021543-350x233.jpg 350w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2271021543-480x320.jpg 480w, https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2271021543-272x182.jpg 272w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para evitar la tr\u00e1gica p\u00e9rdida de millones de ni\u00f1os y adolescentes que se prev\u00e9 si este <em>statu quo <\/em>contin\u00faa, el mundo tiene que acelerar sus esfuerzos por reducir la mortalidad infantil por medio del cuidado continuado infantil, comenzando con la atenci\u00f3n prenatal (<em>Informe sobre mortalidad infantil<\/em>, 2022). Seg\u00fan la Organizaci\u00f3n Mundial de la Salud, es esencial promover la lactancia materna inmediata y exclusiva, as\u00ed como tambi\u00e9n formar a los involucrados en el cuidado prenatal, natal y postnatal con el fin de atajar las causas m\u00e1s evitables de muerte entre menores de cinco a\u00f1os.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acceso a una nutrici\u00f3n adecuada y el consumo de micronutrientes tambi\u00e9n desempe\u00f1an un papel muy importante en la esperanza de vida de los ni\u00f1os, junto a las condiciones medioambientales en las que el ni\u00f1o vive (acceso a agua y saneamiento) y al reconocimiento de la familia de s\u00edntomas peligrosos en la salud del ni\u00f1o (World Vision, 2016). Aunque el n\u00famero de defunciones infantiles en el mundo es muy elevado, es posible garantizar la supervivencia de todos los ni\u00f1os con las inversiones, la voluntad y las pol\u00edticas apropiadas (<em>Informe sobre mortalidad infantil<\/em>, 2022).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Escrito por Arianna Braga<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Revisado internamente por Aditi Partha&nbsp;<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Traducido por Celia Mart\u00ednez Coronado<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Revisado por Cristina Morillo Berral<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>\u00daltima modificaci\u00f3n el 22 de octubre de 2023<\/strong><\/em><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Bibliograf\u00eda:<\/strong><\/h4>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Child and youth mortality data ages 5-24, UNICEF, (2023). Child and youth mortality data ages 5-24. Retrieved from UNICEF at <a href=\"https:\/\/data.unicef.org\/topic\/child-survival\/child-and-youth-mortality-age-5-24\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/data.unicef.org\/topic\/child-survival\/child-and-youth-mortality-age-5-24\/<\/a>, accessed on 22 October 2023.&nbsp;<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Child Mortality Report (2022). Levels and trends in child mortality. Report 2022. Estimates developed by the United Nations Inter-agency Group for Child Mortality Estimation. Retrieved from UNICEF at https:\/\/data.unicef.org\/resources\/levels-and-trends-in-child-mortality\/, accessed on 22 October 2023.&nbsp;<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Child mortality under 5 years, WHO (2022). Child mortality (under 5 years). Retrieved from WHO at <a href=\"https:\/\/www.who.int\/news-room\/fact-sheets\/detail\/levels-and-trends-in-child-under-5-mortality-in-2020\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.who.int\/news-room\/fact-sheets\/detail\/levels-and-trends-in-child-under-5-mortality-in-2020<\/a>, accessed on 22 October 2023.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Child survival and the SDGs, UNICEF (2023). Child survival and the SDGs. Retrieved from UNICEF at <a href=\"https:\/\/data.unicef.org\/topic\/child-survival\/child-survival-sdgs\/,\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/data.unicef.org\/topic\/child-survival\/child-survival-sdgs\/,<\/a> accessed on 22 October 2023.&nbsp;<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Mortality among children aged 5-14 years, WHO (2019). Mortality among children aged 5-14 years. Retrieved from WHO at <a href=\"https:\/\/www.who.int\/news-room\/fact-sheets\/detail\/mortality-among-children-aged-5-14-years\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.who.int\/news-room\/fact-sheets\/detail\/mortality-among-children-aged-5-14-years<\/a>, accessed on 22 October 2023.&nbsp;<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Neonatal mortality, UNICEF (2023). Neonatal mortality. Retrieved from UNICEF at <a href=\"https:\/\/data.unicef.org\/topic\/child-survival\/neonatal-mortality\/#resources\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/data.unicef.org\/topic\/child-survival\/neonatal-mortality\/#resources<\/a>, accessed on 22 October 2023.&nbsp;<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Newborn Mortality, WHO (2022). Newborn Mortality. Retrieved from WHO at <a href=\"https:\/\/www.who.int\/news-room\/fact-sheets\/detail\/levels-and-trends-in-child-mortality-report-2021\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.who.int\/news-room\/fact-sheets\/detail\/levels-and-trends-in-child-mortality-report-2021<\/a>, accessed on 22 October 2023.&nbsp;<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Older adolescent, WHO (2022). Older adolescent (15 to 19 years) and young adult (20 to 24 years) mortality. Retrieved from WHO at https:\/\/www.who.int\/news-room\/fact-sheets\/detail\/levels-and-trends-in-older-adolescent-(15-to-19-years)-and-young-adult-(20-to-24-years)-mortality, accessed on 22 October 2023.&nbsp;<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">UNICEF, Under-five mortality (2023). Under-five mortality. Retrieved from UNICEF at <a href=\"https:\/\/data.unicef.org\/topic\/child-survival\/under-five-mortality\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/data.unicef.org\/topic\/child-survival\/under-five-mortality\/<\/a>, accessed on 22 October 2023.&nbsp;<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">WHO (2023). SDG Target 3.2: End preventable deaths of newborns and children under 5 years of age. Retrieved from WHO at <a href=\"https:\/\/www.who.int\/data\/gho\/data\/themes\/topics\/sdg-target-3_2-newborn-and-child-mortality\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.who.int\/data\/gho\/data\/themes\/topics\/sdg-target-3_2-newborn-and-child-mortality<\/a>, accessed on 22 October 2023.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">World Vision (2016). Child mortality: Top causes, best solutions. Retrieved from World Vision at <a href=\"https:\/\/www.worldvision.org\/health-news-stories\/child-mortality-causes-solutions\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.worldvision.org\/health-news-stories\/child-mortality-causes-solutions<\/a>, accessed on 14 November 2023.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gracias a algunos esfuerzos notables por garantizar la supervivencia infantil sostenible, el mundo ha reconocido y avanzado hacia el pleno disfrute del derecho a la vida de todo ni\u00f1o. Sin embargo, en 2021, cinco millones de ni\u00f1os no llegaron a cumplir los cinco a\u00f1os a nivel mundial, por tanto, a\u00fan quedan desaf\u00edos pendientes en lo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19051,"parent":346,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-479","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mortalidad infantil - Humanium<\/title>\n<meta name=\"description\" content=\"Cinco millones de ni\u00f1os de todo el mundo no llegaron a cumplir los cinco a\u00f1os en 2021, lo que demuestra la prevalencia de la mortalidad infantil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/salud\/mortalidad-infantil\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mortalidad infantil - Humanium\" \/>\n<meta property=\"og:description\" content=\"Cinco millones de ni\u00f1os de todo el mundo no llegaron a cumplir los cinco a\u00f1os en 2021, lo que demuestra la prevalencia de la mortalidad infantil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/salud\/mortalidad-infantil\/\" \/>\n<meta property=\"og:site_name\" content=\"Humanium\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-20T17:24:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2416028877-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/enfoques-tematicos\\\/salud\\\/mortalidad-infantil\\\/\",\"url\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/enfoques-tematicos\\\/salud\\\/mortalidad-infantil\\\/\",\"name\":\"Mortalidad infantil - Humanium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/enfoques-tematicos\\\/salud\\\/mortalidad-infantil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/enfoques-tematicos\\\/salud\\\/mortalidad-infantil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/shutterstock_2416028877-scaled.jpg\",\"datePublished\":\"2012-12-05T10:40:34+00:00\",\"dateModified\":\"2026-08-20T17:24:39+00:00\",\"description\":\"Cinco millones de ni\u00f1os de todo el mundo no llegaron a cumplir los cinco a\u00f1os en 2021, lo que demuestra la prevalencia de la mortalidad infantil.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/enfoques-tematicos\\\/salud\\\/mortalidad-infantil\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.humanium.org\\\/es\\\/enfoques-tematicos\\\/salud\\\/mortalidad-infantil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/enfoques-tematicos\\\/salud\\\/mortalidad-infantil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/shutterstock_2416028877-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/shutterstock_2416028877-scaled.jpg\",\"width\":2560,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/enfoques-tematicos\\\/salud\\\/mortalidad-infantil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enfoques tem\u00e1ticos\",\"item\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/enfoques-tematicos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Salud\",\"item\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/enfoques-tematicos\\\/salud\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Mortalidad infantil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/\",\"name\":\"Humanium\",\"description\":\"\u00a1Los ni\u00f1os primero!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.humanium.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mortalidad infantil - Humanium","description":"Cinco millones de ni\u00f1os de todo el mundo no llegaron a cumplir los cinco a\u00f1os en 2021, lo que demuestra la prevalencia de la mortalidad infantil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/salud\/mortalidad-infantil\/","og_locale":"es_ES","og_type":"article","og_title":"Mortalidad infantil - Humanium","og_description":"Cinco millones de ni\u00f1os de todo el mundo no llegaron a cumplir los cinco a\u00f1os en 2021, lo que demuestra la prevalencia de la mortalidad infantil.","og_url":"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/salud\/mortalidad-infantil\/","og_site_name":"Humanium","article_modified_time":"2026-08-20T17:24:39+00:00","og_image":[{"width":2560,"height":1350,"url":"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2416028877-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/salud\/mortalidad-infantil\/","url":"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/salud\/mortalidad-infantil\/","name":"Mortalidad infantil - Humanium","isPartOf":{"@id":"https:\/\/www.humanium.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/salud\/mortalidad-infantil\/#primaryimage"},"image":{"@id":"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/salud\/mortalidad-infantil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2416028877-scaled.jpg","datePublished":"2012-12-05T10:40:34+00:00","dateModified":"2026-08-20T17:24:39+00:00","description":"Cinco millones de ni\u00f1os de todo el mundo no llegaron a cumplir los cinco a\u00f1os en 2021, lo que demuestra la prevalencia de la mortalidad infantil.","breadcrumb":{"@id":"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/salud\/mortalidad-infantil\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.humanium.org\/es\/enfoques-tematicos\/salud\/mortalidad-infantil\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/salud\/mortalidad-infantil\/#primaryimage","url":"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2416028877-scaled.jpg","contentUrl":"https:\/\/www.humanium.org\/es\/wp-content\/uploads\/2024\/08\/shutterstock_2416028877-scaled.jpg","width":2560,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/salud\/mortalidad-infantil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.humanium.org\/es\/"},{"@type":"ListItem","position":2,"name":"Enfoques tem\u00e1ticos","item":"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/"},{"@type":"ListItem","position":3,"name":"Salud","item":"https:\/\/www.humanium.org\/es\/enfoques-tematicos\/salud\/"},{"@type":"ListItem","position":4,"name":"Mortalidad infantil"}]},{"@type":"WebSite","@id":"https:\/\/www.humanium.org\/es\/#website","url":"https:\/\/www.humanium.org\/es\/","name":"Humanium","description":"\u00a1Los ni\u00f1os primero!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.humanium.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/pages\/479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/comments?post=479"}],"version-history":[{"count":14,"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/pages\/479\/revisions"}],"predecessor-version":[{"id":22281,"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/pages\/479\/revisions\/22281"}],"up":[{"embeddable":true,"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/pages\/346"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/media\/19051"}],"wp:attachment":[{"href":"https:\/\/www.humanium.org\/es\/wp-json\/wp\/v2\/media?parent=479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}